{"id":46789,"date":"2026-05-26T23:43:09","date_gmt":"2026-05-26T23:43:09","guid":{"rendered":"https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/"},"modified":"2026-05-28T19:10:47","modified_gmt":"2026-05-28T19:10:47","slug":"broca-sds-plus-dewalt-14x160mm","status":"publish","type":"product","link":"https:\/\/www.elencocompleto.pt\/en\/product\/broca-sds-plus-dewalt-14x160mm\/","title":{"rendered":"BROCA SDS PLUS DEWALT 14X160MM"},"content":{"rendered":"<div><font color=\"#666666\" face=\"Arial, Helvetica, sans-serif\"><b>BROCA SDS PLUS DEWALT 14X160MM<br \/><\/b><\/font><\/div>\n<div><font color=\"#666666\" face=\"Arial, Helvetica, sans-serif\"><span><br \/><\/span><\/font><\/div>\n<ul>\n<li>As Brocas SDS-Plus Extreme 2 s\u00e3o a melhor escolha em termos de velocidade de perfura\u00e7\u00e3o e durabilidade elevada.<\/li>\n<li>Pastilha de grande dureza projectada para elevada durabilidade<\/li>\n<li>Novo design da espiral proporciona uma remo\u00e7\u00e3o r\u00e1pida do material<\/li>\n<li>Corpo de grande dureza para maior resist\u00eancia<\/li>\n<li>Nova pastilha de 160\u00ba proporciona maior vida \u00fatil e maior rapidez de perfura\u00e7\u00e3o<\/li>\n<\/ul>\n<div class=\"productdetail_features_headlines\">ESPECIFICA\u00c7\u00d5ES<\/div>\n<div class=\"productdetail_specifications_table_container\">\n<table summary=\"DT9504 Especifica\u00e7\u00f5es\" class=\"productdetail_specifications_table\">\n<tbody>\n<tr>\n<td>Di\u00e2metro<\/td>\n<td>14 mm<\/td>\n<\/tr>\n<tr>\n<td>Comprimento<\/td>\n<td>160 mm<\/td>\n<\/tr>\n<tr>\n<td>Alturas de trabalho<\/td>\n<td>100 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>BROCA SDS PLUS DEWALT 14X160MMAs Brocas SDS-Plus Extreme 2 s\u00e3o a melhor escolha em termos de velocidade de perfura\u00e7\u00e3o e durabilidade elevada.Pastilha de grande dureza projectada para elevada dur&#8230;<\/p>","protected":false},"featured_media":46788,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[{"term_id":779,"name":"DeWalt","slug":"marca-dewalt","term_group":0,"term_taxonomy_id":779,"taxonomy":"brand","description":"Ferramentas el\u00e9tricas profissionais e acess\u00f3rios","parent":0,"count":224,"filter":"raw"}],"product_brand":[],"product_cat":[517,571,570],"product_tag":[99],"class_list":["post-46789","product","type-product","status-publish","has-post-thumbnail","brand-marca-dewalt","product_cat-bricolage-e-ferramentas","product_cat-brocas-ferro-madeira-pedra-betao-etc","product_cat-ferramentas-de-corte-brocas","product_tag-04-2023","pa_marca-dewalt","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BROCA SDS PLUS DEWALT 14X160MM - Elenco Completo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elencocompleto.pt\/en\/product\/broca-sds-plus-dewalt-14x160mm\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BROCA SDS PLUS DEWALT 14X160MM - Elenco Completo\" \/>\n<meta property=\"og:description\" content=\"BROCA SDS PLUS DEWALT 14X160MMAs Brocas SDS-Plus Extreme 2 s\u00e3o a melhor escolha em termos de velocidade de perfura\u00e7\u00e3o e durabilidade elevada.Pastilha de grande dureza projectada para elevada dur&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elencocompleto.pt\/en\/product\/broca-sds-plus-dewalt-14x160mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Elenco Completo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T19:10:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elencocompleto.pt\/wp-content\/uploads\/2026\/05\/DT9566-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"601\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/product\\\/broca-sds-plus-dewalt-14x160mm\\\/\",\"url\":\"https:\\\/\\\/www.elencocompleto.pt\\\/product\\\/broca-sds-plus-dewalt-14x160mm\\\/\",\"name\":\"BROCA SDS PLUS DEWALT 14X160MM - Elenco Completo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/product\\\/broca-sds-plus-dewalt-14x160mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/product\\\/broca-sds-plus-dewalt-14x160mm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elencocompleto.pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DT9566-1.jpg\",\"datePublished\":\"2026-05-26T23:43:09+00:00\",\"dateModified\":\"2026-05-28T19:10:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/product\\\/broca-sds-plus-dewalt-14x160mm\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elencocompleto.pt\\\/product\\\/broca-sds-plus-dewalt-14x160mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/product\\\/broca-sds-plus-dewalt-14x160mm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.elencocompleto.pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DT9566-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.elencocompleto.pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DT9566-1.jpg\",\"width\":601,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/product\\\/broca-sds-plus-dewalt-14x160mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.elencocompleto.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/www.elencocompleto.pt\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BROCA SDS PLUS DEWALT 14X160MM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/#website\",\"url\":\"https:\\\/\\\/www.elencocompleto.pt\\\/\",\"name\":\"Elenco Completo\",\"description\":\"Ferramentas, Bricolage e Equipamentos \u2014 Loja Online em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elencocompleto.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/#organization\",\"name\":\"Elenco Completo\",\"url\":\"https:\\\/\\\/www.elencocompleto.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.elencocompleto.pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Link-\u2192-Logo-footer.svg-1.png\",\"contentUrl\":\"https:\\\/\\\/www.elencocompleto.pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Link-\u2192-Logo-footer.svg-1.png\",\"width\":234,\"height\":56,\"caption\":\"Elenco Completo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elencocompleto.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BROCA SDS PLUS DEWALT 14X160MM - Elenco Completo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elencocompleto.pt\/en\/product\/broca-sds-plus-dewalt-14x160mm\/","og_locale":"en_US","og_type":"article","og_title":"BROCA SDS PLUS DEWALT 14X160MM - Elenco Completo","og_description":"BROCA SDS PLUS DEWALT 14X160MMAs Brocas SDS-Plus Extreme 2 s\u00e3o a melhor escolha em termos de velocidade de perfura\u00e7\u00e3o e durabilidade elevada.Pastilha de grande dureza projectada para elevada dur&#8230;","og_url":"https:\/\/www.elencocompleto.pt\/en\/product\/broca-sds-plus-dewalt-14x160mm\/","og_site_name":"Elenco Completo","article_modified_time":"2026-05-28T19:10:47+00:00","og_image":[{"width":601,"height":600,"url":"https:\/\/www.elencocompleto.pt\/wp-content\/uploads\/2026\/05\/DT9566-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/","url":"https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/","name":"BROCA SDS PLUS DEWALT 14X160MM - Elenco Completo","isPartOf":{"@id":"https:\/\/www.elencocompleto.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/#primaryimage"},"image":{"@id":"https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elencocompleto.pt\/wp-content\/uploads\/2026\/05\/DT9566-1.jpg","datePublished":"2026-05-26T23:43:09+00:00","dateModified":"2026-05-28T19:10:47+00:00","breadcrumb":{"@id":"https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/#primaryimage","url":"https:\/\/www.elencocompleto.pt\/wp-content\/uploads\/2026\/05\/DT9566-1.jpg","contentUrl":"https:\/\/www.elencocompleto.pt\/wp-content\/uploads\/2026\/05\/DT9566-1.jpg","width":601,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.elencocompleto.pt\/product\/broca-sds-plus-dewalt-14x160mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.elencocompleto.pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/www.elencocompleto.pt\/shop\/"},{"@type":"ListItem","position":3,"name":"BROCA SDS PLUS DEWALT 14X160MM"}]},{"@type":"WebSite","@id":"https:\/\/www.elencocompleto.pt\/#website","url":"https:\/\/www.elencocompleto.pt\/","name":"Elenco Completo","description":"Ferramentas, Bricolage e Equipamentos \u2014 Loja Online em Portugal","publisher":{"@id":"https:\/\/www.elencocompleto.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elencocompleto.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.elencocompleto.pt\/#organization","name":"Elenco Completo","url":"https:\/\/www.elencocompleto.pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.elencocompleto.pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.elencocompleto.pt\/wp-content\/uploads\/2026\/05\/Link-\u2192-Logo-footer.svg-1.png","contentUrl":"https:\/\/www.elencocompleto.pt\/wp-content\/uploads\/2026\/05\/Link-\u2192-Logo-footer.svg-1.png","width":234,"height":56,"caption":"Elenco Completo"},"image":{"@id":"https:\/\/www.elencocompleto.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/product\/46789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/comments?post=46789"}],"version-history":[{"count":0,"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/product\/46789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/media\/46788"}],"wp:attachment":[{"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/media?parent=46789"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/etheme_brands?post=46789"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/product_brand?post=46789"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/product_cat?post=46789"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.elencocompleto.pt\/en\/wp-json\/wp\/v2\/product_tag?post=46789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}